{"id":1393,"date":"2021-02-02T10:44:37","date_gmt":"2021-02-02T10:44:37","guid":{"rendered":"http:\/\/zphceramex.pl\/?post_type=dt_portfolio&#038;p=1393"},"modified":"2021-02-15T11:33:58","modified_gmt":"2021-02-15T11:33:58","slug":"graygraphite","status":"publish","type":"dt_portfolio","link":"https:\/\/zphceramex.pl\/en\/produkt\/graygraphite\/","title":{"rendered":"&#8211; Gray &#038; Graphite &#8211;"},"content":{"rendered":"<p>[vc_row][vc_column]<div id=\"ultimate-heading-10096a572ca7905fa\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-10096a572ca7905fa uvc-5296  uvc-heading-default-font-sizes\" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-10096a572ca7905fa h3'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h3 style=\"--font-weight:theme;margin-bottom:20px;\"><strong>Gray &amp; Graphite <\/strong>Collection<\/h3><\/div><\/div>[vc_row_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]Figures of snowmen and Holy Family, all in matt colours. Christmas Trees and snowmen finished with glitter. Ceramic baubles with a winter landscape. All painted in different shades of silver, graphite, white.[\/vc_column_text][vc_single_image image=&#8221;1490&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]\n<table id=\"tablepress-23\" class=\"tablepress tablepress-id-23\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">ID<\/th><th class=\"column-2\">catalog number<\/th><th class=\"column-3\">H<\/th><th class=\"column-4\">W<\/th><th class=\"column-5\">D<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">4342.2<\/td><td class=\"column-3\">40<\/td><td class=\"column-4\">8,5<\/td><td class=\"column-5\">8,5<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">4705.1<\/td><td class=\"column-3\">74<\/td><td class=\"column-4\">17<\/td><td class=\"column-5\">17<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">4335.2<\/td><td class=\"column-3\">60<\/td><td class=\"column-4\">12<\/td><td class=\"column-5\">12<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">4700.5<\/td><td class=\"column-3\">105<\/td><td class=\"column-4\">20<\/td><td class=\"column-5\">20<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">4200.2<\/td><td class=\"column-3\">68<\/td><td class=\"column-4\">27<\/td><td class=\"column-5\">17<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">4885.5<\/td><td class=\"column-3\">38<\/td><td class=\"column-4\">21<\/td><td class=\"column-5\">23<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">4710.5<\/td><td class=\"column-3\">54<\/td><td class=\"column-4\">10<\/td><td class=\"column-5\">10<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">4880.5<\/td><td class=\"column-3\">38<\/td><td class=\"column-4\">26<\/td><td class=\"column-5\">19<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">3040.2<\/td><td class=\"column-3\">20<\/td><td class=\"column-4\">18<\/td><td class=\"column-5\">18<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">4820.9<\/td><td class=\"column-3\">24<\/td><td class=\"column-4\">27,5<\/td><td class=\"column-5\">17,5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_row_inner][vc_column_inner width=&#8221;3\/4&#8243;][vc_column_text]Figures of snowmen and Holy Family, all in matt colours. Christmas Trees and snowmen finished with glitter. Ceramic baubles with a winter landscape. All painted in different shades of silver, graphite, white.[\/vc_column_text][vc_single_image image=&#8221;1490&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":3,"featured_media":1471,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[45],"dt_portfolio_tags":[],"class_list":["post-1393","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-colour-sets","dt_portfolio_category-45","description-off"],"_links":{"self":[{"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/dt_portfolio\/1393\/"}],"collection":[{"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/dt_portfolio\/"}],"about":[{"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/types\/dt_portfolio\/"}],"author":[{"embeddable":true,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/users\/3\/"}],"replies":[{"embeddable":true,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/comments\/?post=1393"}],"version-history":[{"count":5,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/dt_portfolio\/1393\/revisions\/"}],"predecessor-version":[{"id":2749,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/dt_portfolio\/1393\/revisions\/2749\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/media\/1471\/"}],"wp:attachment":[{"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/media\/?parent=1393"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/dt_portfolio_category\/?post=1393"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/zphceramex.pl\/en\/wp-json\/wp\/v2\/dt_portfolio_tags\/?post=1393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}